{"id":106,"date":"2015-05-05T22:50:49","date_gmt":"2015-05-05T22:50:49","guid":{"rendered":"http:\/\/marialaet.com\/?post_type=obra&#038;p=106"},"modified":"2025-11-27T21:53:56","modified_gmt":"2025-11-27T21:53:56","slug":"terra-canudos_video","status":"publish","type":"obra","link":"https:\/\/marialaet.com\/en\/obra\/terra-canudos_video\/","title":{"rendered":"Earth (Canudos)"},"content":{"rendered":"","protected":false},"featured_media":703,"template":"","tecnica":[15],"class_list":["post-106","obra","type-obra","status-publish","has-post-thumbnail","hentry","tecnica-video"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/obra\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/obra"}],"about":[{"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/types\/obra"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/media\/703"}],"wp:attachment":[{"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/media?parent=106"}],"wp:term":[{"taxonomy":"tecnica","embeddable":true,"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/tecnica?post=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}