{"id":1989,"date":"2023-12-29T19:33:38","date_gmt":"2023-12-29T19:33:38","guid":{"rendered":"http:\/\/marialaet.com\/?post_type=obra&#038;p=1989"},"modified":"2024-01-29T19:42:53","modified_gmt":"2024-01-29T19:42:53","slug":"terra-jardim-burle-marx-mam-rio","status":"publish","type":"obra","link":"https:\/\/marialaet.com\/en\/obra\/terra-jardim-burle-marx-mam-rio\/","title":{"rendered":"Earth (Burle Marx Garden, MAM Rio)"},"content":{"rendered":"","protected":false},"featured_media":1984,"template":"","tecnica":[13],"class_list":["post-1989","obra","type-obra","status-publish","has-post-thumbnail","hentry","tecnica-fotografia"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/obra\/1989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/obra"}],"about":[{"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/types\/obra"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/media\/1984"}],"wp:attachment":[{"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/media?parent=1989"}],"wp:term":[{"taxonomy":"tecnica","embeddable":true,"href":"https:\/\/marialaet.com\/en\/wp-json\/wp\/v2\/tecnica?post=1989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}